{"id":2891,"date":"2021-12-21T19:09:25","date_gmt":"2021-12-21T19:09:25","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/12\/21\/sap-investe-r-11-milhoes-na-modernizacao-do-parque-tecnologico\/"},"modified":"2021-12-21T19:09:25","modified_gmt":"2021-12-21T19:09:25","slug":"sap-investe-r-11-milhoes-na-modernizacao-do-parque-tecnologico","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/sap-investe-r-11-milhoes-na-modernizacao-do-parque-tecnologico\/","title":{"rendered":"SAP investe R$ 11 milh\u00f5es na moderniza\u00e7\u00e3o do parque tecnol\u00f3gico"},"content":{"rendered":"<\/p>\n<p style=\"text-align: justify;\">A Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa (SAP) fez um investimento de R$ 11,4 milh\u00f5es para renovar e ampliar seu parque tecnol\u00f3gico. Nesta ter\u00e7a-feira (21) o Secret\u00e1rio da SAP, Leandro Lima, fez a entrega simb\u00f3lica de equipamentos que ir\u00e3o atender as novas necessidades dos Sistemas Prisional e Socioeducativo. \u201cUma das li\u00e7\u00f5es da pandemia nos trouxe foi a necessidade de nos adaptarmos \u00e0 realidade de forma r\u00e1pida e assertiva. Ao mesmo tempo em que era fundamental reduzir o tr\u00e2nsito de pessoas nas unidades t\u00ednhamos que garantir o contato do interno com seu advogado, com seus familiares, com o Poder Judici\u00e1rio e a \u00fanica alternativa era o meio digital\u201d, disse o Secret\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">Neste sentido, a SAP adquiriu 2,1 mil computadores completos \u2013 sendo que 1,6 mil j\u00e1 foram instalados nas unidades e ou 400 ser\u00e3o entregues nos pr\u00f3ximos dias para as unidades que integram o Departamento de Pol\u00edcia Penal (DPP) e o Departamento de Administra\u00e7\u00e3o Socioeducativo (Dease), em todo o estado. Outros 200 tablets tamb\u00e9m est\u00e3o sendo encaminhados \u00e0s unidades prisionais e socioeducativas.<\/p>\n<p style=\"text-align: justify;\">Por meio de parcerias com a OAB\/SC e com o Poder Judici\u00e1rio, a SAP deu prosseguimento ao projeto de implantar salas para videoaudi\u00eancia, os parlat\u00f3rios virtuais para advogados e as salas de visita virtual para o contato entre internos e seus familiares, entre outras demandas administrativas, visto que todos os processos tramitam por meio digital. \u201cTivemos que melhorar a velocidade de nossas redes de internet e, para isso, estamos entregando 1 mil acces point que s\u00e3o dispositivos de rede que permitem levar o sinal de Internet a \u00e1reas em que a cobertura original proporcionada por um roteador \u00e9 limitada\u201d, explicou o Secret\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">O estudo sobre a demanda por realizado pela equipe da Ger\u00eancia de Tecnologia da Informa\u00e7\u00e3o (Getin), sob a coordena\u00e7\u00e3o do Policial Penal Rafael Bittencourt. \u201cCom os novos equipamentos e o aumento da capacidade de internet podemos garantir a estabilidade da rede visto que os Sistemas Prisional e Socioeducativo n\u00e3o podem prescindir de informa\u00e7\u00f5es\u201d, observou Rafael Bittencourt.<\/p>\n<p style=\"text-align: justify;\">Participaram da solenidade de entrega dos equipamentos o Diretor de Administra\u00e7\u00e3o e Finan\u00e7as Bruno Gabriel, Diretor do Departamento de Pol\u00edcia Penal, Vladecir dos Santos, Diretor do Departamento de Administra\u00e7\u00e3o Socioeducativa, Zeno Tressoldi e o Gerente de Tecnologia da Informa\u00e7\u00e3o, Rafael Bittencourt.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-731\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2021\/12\/Foto_investimento_1-d26.jpg\" alt=\"Foto investimento 1\" width=\"549\" height=\"436\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa (SAP) fez um investimento de R$ 11,4 milh\u00f5es para renovar e ampliar seu parque tecnol\u00f3gico. Nesta ter\u00e7a-feira (21) o Secret\u00e1rio da SAP, Leandro Lima, fez a entrega simb\u00f3lica de equipamentos que ir\u00e3o atender as novas necessidades dos Sistemas Prisional e Socioeducativo. \u201cUma das li\u00e7\u00f5es da pandemia nos trouxe [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:26:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2891"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2891"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/730"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}