{"id":2804,"date":"2020-11-16T19:01:09","date_gmt":"2020-11-16T19:01:09","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2020\/11\/16\/dease-entrega-coturnos-e-coletes-balisticos-aos-agentes-de-seguranca-socioeducativos\/"},"modified":"2020-11-16T19:01:09","modified_gmt":"2020-11-16T19:01:09","slug":"dease-entrega-coturnos-e-coletes-balisticos-aos-agentes-de-seguranca-socioeducativos","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/dease-entrega-coturnos-e-coletes-balisticos-aos-agentes-de-seguranca-socioeducativos\/","title":{"rendered":"Dease entrega coturnos e coletes bal\u00edsticos aos Agentes de Seguran\u00e7a Socioeducativos"},"content":{"rendered":"<p dir=\"ltr\" style=\"line-height: 1.38; margin-top: 0pt; margin-bottom: 10pt; text-align: justify;\">A Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa \u2013 SAP deu in\u00edcio em novembro de 2020, a entrega das botas t\u00e1ticas aos Agentes de Seguran\u00e7a Socioeducativos de Santa Catarina.<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; margin-top: 0pt; margin-bottom: 10pt;\">Na qual a Ger\u00eancia de Patrim\u00f4nio \u2013 GEPAT\/SAP&nbsp; ficou respons\u00e1vel pela distribui\u00e7\u00e3o das botas para as unidades onde os servidores estavam lotados.&nbsp; Todos os Agentes de Seguran\u00e7a Socioeducativos receber\u00e3o um par de coturnos, independente se concursados ou ACTs.<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; margin-top: 0pt; margin-bottom: 10pt;\">A aquisi\u00e7\u00e3o desses bens \u00e9 objeto do preg\u00e3o eletr\u00f4nico PE 066\/SJC\/2018, sendo de suma import\u00e2ncia ao pleno desenvolvimento das atribui\u00e7\u00f5es que o cargo de Agente de Seguran\u00e7a Socioeducativo exige.&nbsp;<\/p>\n<p dir=\"ltr\" style=\"line-height: 1.38; text-align: justify; margin-top: 0pt; margin-bottom: 10pt;\">No m\u00eas de outubro do corrente ano foram entregues 690 coletes bal\u00edsticos aos Agentes. Cada Agente efetivo tem um colete acautelado em seu nome, os Agentes ACTs far\u00e3o o uso de coletes acautelados para a Unidade Socioeducativa.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa \u2013 SAP deu in\u00edcio em novembro de 2020, a entrega das botas t\u00e1ticas aos Agentes de Seguran\u00e7a Socioeducativos de Santa Catarina. Na qual a Ger\u00eancia de Patrim\u00f4nio \u2013 GEPAT\/SAP&nbsp; ficou respons\u00e1vel pela distribui\u00e7\u00e3o das botas para as unidades onde os servidores estavam lotados.&nbsp; Todos os Agentes [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":515,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:02:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2804"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2804"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/515"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}