{"id":24444,"date":"2026-03-26T13:28:38","date_gmt":"2026-03-26T16:28:38","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=24444"},"modified":"2026-03-26T13:28:38","modified_gmt":"2026-03-26T16:28:38","slug":"policia-penal-realiza-escolta-interestadual-e-movimenta-custodiados-entre-santa-catarina-e-parana","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/policia-penal-realiza-escolta-interestadual-e-movimenta-custodiados-entre-santa-catarina-e-parana\/","title":{"rendered":"Pol\u00edcia Penal realiza escolta interestadual e movimenta custodiados entre Santa Catarina e Paran\u00e1"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\">A Pol\u00edcia Penal de Santa Catarina realizou, na madrugada desta ter\u00e7a-feira, uma opera\u00e7\u00e3o de escolta interestadual que mobilizou equipes especializadas e refor\u00e7ou a atua\u00e7\u00e3o integrada entre os estados. Ao todo, foram movimentados 55 custodiados, sendo 29 transferidos de Santa Catarina para o Paran\u00e1 e 26 do Paran\u00e1 para Santa Catarina.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Coordenada pela Diretoria de Seguran\u00e7a e Opera\u00e7\u00f5es (DSO), a a\u00e7\u00e3o contou com a participa\u00e7\u00e3o do Servi\u00e7o de Opera\u00e7\u00f5es e Escoltas (SOE), dos N\u00facleos de Opera\u00e7\u00f5es T\u00e1ticas (NOTs) de todas as regi\u00f5es catarinenses, al\u00e9m da integra\u00e7\u00e3o com o SOE do Paran\u00e1 e apoio do Departamento Penitenci\u00e1rio Nacional (DPEM). As equipes atuaram de forma coordenada para garantir a execu\u00e7\u00e3o segura de toda a log\u00edstica de transporte e recambiamento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Reconhecida pela atua\u00e7\u00e3o estrat\u00e9gica, a Pol\u00edcia Penal desempenha papel essencial na cust\u00f3dia e movimenta\u00e7\u00e3o de presos, sendo respons\u00e1vel por opera\u00e7\u00f5es de alta complexidade. A escolta interestadual exige planejamento detalhado, preparo t\u00e9cnico e integra\u00e7\u00e3o entre for\u00e7as, assegurando a integridade dos servidores, dos custodiados e da sociedade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante a opera\u00e7\u00e3o, havia custodiados de elevada periculosidade, cuja condu\u00e7\u00e3o ficou sob responsabilidade do Servi\u00e7o de Opera\u00e7\u00f5es e Escoltas (SOE), equipe especializada treinada para atuar em situa\u00e7\u00f5es que demandam protocolos rigorosos de seguran\u00e7a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A opera\u00e7\u00e3o foi estruturada de forma concentrada, tendo como pontos principais o Pres\u00eddio Regional de Joinville e a Penitenci\u00e1ria de Integra\u00e7\u00e3o Social de Piraquara (PISP), unidade respons\u00e1vel pelo recebimento e redistribui\u00e7\u00e3o interna dos custodiados.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A a\u00e7\u00e3o transcorreu sem intercorr\u00eancias, com total preserva\u00e7\u00e3o da integridade f\u00edsica dos envolvidos e rigoroso cumprimento dos protocolos de seguran\u00e7a estabelecidos para esse tipo de opera\u00e7\u00e3o.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para a secret\u00e1ria de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, Danielle Amorim Silva, a a\u00e7\u00e3o \u00e9 estrat\u00e9gica para aliviar a press\u00e3o sobre o sistema prisional catarinense. \u201cEstamos trabalhando de forma cont\u00ednua para devolver aos seus estados de origem os custodiados que est\u00e3o presos exclusivamente por processos de outras unidades da federa\u00e7\u00e3o, sem qualquer v\u00ednculo processual em Santa Catarina. Esse movimento \u00e9 fundamental para desafogar o sistema prisional e garantir melhores condi\u00e7\u00f5es de gest\u00e3o e seguran\u00e7a nas nossas unidades\u201d, destacou.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Atualmente, o sistema prisional catarinense abriga 1.833 presos provenientes de diferentes estados da federa\u00e7\u00e3o, custodiados exclusivamente por processos vinculados a outras unidades da federa\u00e7\u00e3o. Diante desse cen\u00e1rio, o Estado tem atuado de forma cont\u00ednua para proceder \u00e0s transfer\u00eancias desses internos para seus locais de origem, contribuindo para a organiza\u00e7\u00e3o do sistema prisional.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A iniciativa refor\u00e7a a aproxima\u00e7\u00e3o institucional entre Santa Catarina e Paran\u00e1, consolidando um modelo eficiente de coopera\u00e7\u00e3o interestadual. O formato adotado, com concentra\u00e7\u00e3o log\u00edstica e redistribui\u00e7\u00e3o planejada, possibilita maior racionaliza\u00e7\u00e3o de recursos e contribui para que os custodiados possam cumprir suas penas em unidades mais pr\u00f3ximas de seus v\u00ednculos familiares, em conson\u00e2ncia com os princ\u00edpios da execu\u00e7\u00e3o penal.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Novas opera\u00e7\u00f5es nesse formato j\u00e1 est\u00e3o previstas, evidenciando a continuidade e o fortalecimento dessa pol\u00edtica integrada de gest\u00e3o penitenci\u00e1ria.\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Penal de Santa Catarina realizou, na madrugada desta ter\u00e7a-feira, uma opera\u00e7\u00e3o de escolta interestadual que mobilizou equipes especializadas e refor\u00e7ou a atua\u00e7\u00e3o integrada entre os estados. Ao todo, foram movimentados 55 custodiados, sendo 29 transferidos de Santa Catarina para o Paran\u00e1 e 26 do Paran\u00e1 para Santa Catarina. Coordenada pela Diretoria de Seguran\u00e7a [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":24445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 23:50:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24444"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=24444"}],"version-history":[{"count":1,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24444\/revisions"}],"predecessor-version":[{"id":24446,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24444\/revisions\/24446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/24445"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=24444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=24444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=24444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}