{"id":22476,"date":"2025-09-24T17:51:59","date_gmt":"2025-09-24T20:51:59","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=22476"},"modified":"2025-09-24T17:51:59","modified_gmt":"2025-09-24T20:51:59","slug":"departamento-da-policia-penal-realiza-curso-de-capacitacao-para-assistentes-sociais-do-sistema-prisional","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/departamento-da-policia-penal-realiza-curso-de-capacitacao-para-assistentes-sociais-do-sistema-prisional\/","title":{"rendered":"Departamento da Pol\u00edcia Penal realiza curso de capacita\u00e7\u00e3o para assistentes sociais do sistema prisional"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>O Departamento da Pol\u00edcia Penal de Santa Catarina deu in\u00edcio, nesta quarta-feira (24), \u00e0 2\u00aa turma do Projeto de Extens\u00e3o para Forma\u00e7\u00e3o e Capacita\u00e7\u00e3o de Assistentes Sociais que atuam nas unidades prisionais do Estado. A iniciativa \u00e9 fruto do Termo de Coopera\u00e7\u00e3o T\u00e9cnica firmado entre o Minist\u00e9rio P\u00fablico do Estado de Santa Catarina (MPSC), a Universidade Federal de Santa Catarina (UFSC), a Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social (Sejuri) e o Conselho Regional de Servi\u00e7o Social de Santa Catarina (CRESS\/SC).<\/em><\/p>\n<p style=\"text-align: justify;\">O curso acontece na Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa (ACAPS), em Florian\u00f3polis, nos dias 24, 25 e 26 de setembro de 2025, no per\u00edodo das 8h \u00e0s 12h e das 13h30 \u00e0s 17h30. Esta segunda edi\u00e7\u00e3o contempla as assistentes sociais das regionais que n\u00e3o participaram da turma inicial.<\/p>\n<p style=\"text-align: justify;\">Com aulas ministradas por professores da UFSC e especialistas convidados, o programa aborda temas relacionados \u00e0s especificidades do trabalho no ambiente prisional, incluindo fundamentos legais, pol\u00edticas p\u00fablicas de reinser\u00e7\u00e3o social e pr\u00e1ticas de atendimento humanizado.<\/p>\n<p style=\"text-align: justify;\">Segundo a Coordena\u00e7\u00e3o de Promo\u00e7\u00e3o Social do Departamento da Pol\u00edcia Penal, o objetivo da capacita\u00e7\u00e3o \u00e9 qualificar a atua\u00e7\u00e3o profissional das assistentes sociais, fortalecer a integra\u00e7\u00e3o entre \u00f3rg\u00e3os parceiros e aprimorar os servi\u00e7os prestados dentro das unidades prisionais.<\/p>\n<p style=\"text-align: justify;\">A expectativa \u00e9 que a iniciativa contribua para a padroniza\u00e7\u00e3o de procedimentos, a troca de experi\u00eancias entre regionais e o fortalecimento do processo de reintegra\u00e7\u00e3o social de pessoas privadas de liberdade.<\/p>","protected":false},"excerpt":{"rendered":"<p>O Departamento da Pol\u00edcia Penal de Santa Catarina deu in\u00edcio, nesta quarta-feira (24), \u00e0 2\u00aa turma do Projeto de Extens\u00e3o para Forma\u00e7\u00e3o e Capacita\u00e7\u00e3o de Assistentes Sociais que atuam nas unidades prisionais do Estado. A iniciativa \u00e9 fruto do Termo de Coopera\u00e7\u00e3o T\u00e9cnica firmado entre o Minist\u00e9rio P\u00fablico do Estado de Santa Catarina (MPSC), a [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":22477,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1315,1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 23:33:58","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22476"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=22476"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/22477"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=22476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=22476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=22476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}