{"id":22422,"date":"2025-09-23T15:43:24","date_gmt":"2025-09-23T18:43:24","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=22422"},"modified":"2025-09-23T15:43:24","modified_gmt":"2025-09-23T18:43:24","slug":"dispensa-de-chamamento-publico-emergencial-028-2025","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/dispensa-de-chamamento-publico-emergencial-028-2025\/","title":{"rendered":"DISPENSA DE CHAMAMENTO P\u00daBLICO EMERGENCIAL 028\/2025"},"content":{"rendered":"<p>Com base na excepcionalidade prevista no inciso I do art. 30 e na forma do art 32, ambos da Lei 13.019\/2014, a qual se aplica subsidiariamente, quanto aos procedimentos, ao chamamento pu\u0301blico para celebrac\u0327a\u0303o de parceria laboral previstas no art. 23 da Lei Complementar 809\/2022, torna pu\u0301blico o extrato da justificativa de Dispensa de Chamamento Pu\u0301blico ( SAP 00106199\/2025), a qual visa a\u0300 formalizac\u0327a\u0303o de Parceria Laboral com a oferta de 40 vagas de trabalho aos presos da PENITENCIARIA MASCULINA DE TUBAR\u00c3O, pelo prazo de 60 meses, com a empresa H.F SISTEMAS DE FREIO LTDA.<\/p>\n<p>Fica concedido o prazo de 5 dias para impugna\u00e7\u00e3o (Lei 13.019\/2014)<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/01_processo-sap-00106199_2025-2\/\" target=\"_blank\" rel=\"noopener\">Extrato<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Com base na excepcionalidade prevista no inciso I do art. 30 e na forma do art 32, ambos da Lei 13.019\/2014, a qual se aplica subsidiariamente, quanto aos procedimentos, ao chamamento pu\u0301blico para celebrac\u0327a\u0303o de parceria laboral previstas no art. 23 da Lei Complementar 809\/2022, torna pu\u0301blico o extrato da justificativa de Dispensa de Chamamento [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:05:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22422"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=22422"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22422\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=22422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=22422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=22422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}