{"id":21443,"date":"2025-06-26T15:22:08","date_gmt":"2025-06-26T18:22:08","guid":{"rendered":"https:\/\/www.sejuri.sc.gov.br\/?p=21443"},"modified":"2025-08-25T13:55:17","modified_gmt":"2025-08-25T16:55:17","slug":"chamamento-publico-no-005-sejuri-gefun-2025","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/chamamento-publico-no-005-sejuri-gefun-2025\/","title":{"rendered":"CHAMAMENTO P\u00daBLICO N\u00ba 005\/SEJURI\/GEFUN\/2025"},"content":{"rendered":"<p>O Estado de Santa Catarina, por meio da Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social (SEJURI), aqui denominado PARCEIRO P\u00daBLICO-INTERVENIENTE e o FUNDO ROTATIVO REGIONAL DA GRANDE FLORIAN\u00d3POLIS (FR01), aqui denominado PARCEIRO P\u00daBLICO-EXECUTOR, tornam p\u00fablico o EDITAL DE PROCESSO SELETIVO (CHAMAMENTO P\u00daBLICO) para celebra\u00e7\u00e3o de instrumentos de parceria com EMPRESAS PRIVADAS COM FINS LUCRATIVOS, cujo objeto \u00e9\u00a0a promo\u00e7\u00e3o de vagas para atividades laborais remuneradas a 160 presos do Sistema Prisional do Estado de Santa Catarina, de acordo com a disponibilidade de vagas previstas na Col\u00f4nia Agroindustrial de Palho\u00e7a, com permiss\u00e3o de uso de tr\u00eas espa\u00e7os medindo 1.600m\u00b2, 1.600m\u00b2 e 2.860m\u00b2 sem edifica\u00e7\u00f5es (nuas), nas condi\u00e7\u00f5es estabelecidas no presente edital, de acordo com o art. 16 e na forma do art. 17, ambos da Lei Complementar n.\u00ba 809\/2022.<\/p>\n<p>ATEN\u00c7\u00c3O: observar a exig\u00eancia de encaminhamento dos documentos mencionados no item 4.4.1 &#8211; Da forma de apresenta\u00e7\u00e3o da proposta.<br \/>\nA proposta e os documentos exigidos dever\u00e3o ser enviados exclusivamente por meio do Formul\u00e1rio eletr\u00f4nico dispon\u00edvel no seguinte endere\u00e7o:\u00a0<a href=\"https:\/\/forms.gle\/FYQgEMgWZMhg1shX7\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/forms.gle\/FYQgEMgWZMhg1shX7&amp;source=gmail&amp;ust=1751047924163000&amp;usg=AOvVaw08GYqrj4pJLeGlnHbT_9aj\">https:\/\/forms.gle\/FYQgEMgWZMhg1shX7<\/a><\/p>\n<p>In\u00edcio das propostas: 27\/06\/2025<br \/>\nPrazo de encerramento: 28\/07\/2025<\/p>\n<ul>\n<li><a href=\"https:\/\/www.sejuri.sc.gov.br\/download\/01_edital-4\/\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li><a href=\"https:\/\/www.sejuri.sc.gov.br\/download\/02_modelo-anexo-ii-pptc\/\" target=\"_blank\" rel=\"noopener\">PPTC<\/a><\/li>\n<li><a href=\"https:\/\/www.sejuri.sc.gov.br\/download\/03_modelo-anexo-iii-questionario-de-investigacao-social-qis\/\" target=\"_blank\" rel=\"noopener\">Question\u00e1rio de Investiga\u00e7\u00e3o Social &#8211; QIS<\/a><\/li>\n<li><a href=\"https:\/\/www.sejuri.sc.gov.br\/download\/04_modelo-anexo-iv-declaracao-de-cumprimento-de-saude-e-seguranca-do-trabalho\/\" target=\"_blank\" rel=\"noopener\">Declara\u00e7\u00e3o de Cumprimento de Sa\u00fade e Seguran\u00e7a do Trabalho<\/a><\/li>\n<li><a href=\"https:\/\/www.sejuri.sc.gov.br\/download\/05_modelo-anexo-v-declaracao-de-menor-empregado\/\" target=\"_blank\" rel=\"noopener\">Declara\u00e7\u00e3o de Menor Empregado<\/a><\/li>\n<li><a href=\"https:\/\/www.sejuri.sc.gov.br\/download\/06_modelo-anexo-vi-declaracao-de-inexistencia-de-trabalho-escravo-e-exploracao-de-mao-de-obra-infantil\/\" target=\"_blank\" rel=\"noopener\">Declara\u00e7\u00e3o de Inexist\u00eancia de Trabalho Escravo e Explora\u00e7\u00e3o de M\u00e3o de Obra Infantil<\/a><\/li>\n<li><a href=\"https:\/\/www.sejuri.sc.gov.br\/download\/07_modelo-anexo-vii-declaracao-de-consulta-ao-municipio-atividade-economica-da-pptc\/\" target=\"_blank\" rel=\"noopener\">Declara\u00e7\u00e3o de Consulta ao Munic\u00edpio &#8211; Atividade Econ\u00f4mica da PPTC<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/08_relatorio-analise-das-propostas-edital-n-005-2025-pdf\/\" target=\"_blank\" rel=\"noopener\">Publica\u00e7\u00e3o Resultado Preliminar &#8211; EDITAL N\u00ba 005\/2025<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/09_homologacao-n-005-2025\/\" target=\"_blank\" rel=\"noopener\">Termo de Homologa\u00e7\u00e3o: Chamamento P\u00fablico 005\/SEJURI\/GEFUN\/2025<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>O Estado de Santa Catarina, por meio da Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social (SEJURI), aqui denominado PARCEIRO P\u00daBLICO-INTERVENIENTE e o FUNDO ROTATIVO REGIONAL DA GRANDE FLORIAN\u00d3POLIS (FR01), aqui denominado PARCEIRO P\u00daBLICO-EXECUTOR, tornam p\u00fablico o EDITAL DE PROCESSO SELETIVO (CHAMAMENTO P\u00daBLICO) para celebra\u00e7\u00e3o de instrumentos de parceria com EMPRESAS PRIVADAS COM FINS LUCRATIVOS, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:17:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/21443"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=21443"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/21443\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=21443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=21443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=21443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}