{"id":2127,"date":"2021-02-01T22:04:35","date_gmt":"2021-02-02T01:04:35","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/edital-n-002-2021-acaps-sap-processo-de-credenciamento-e-selecao-de-servidor-docente\/"},"modified":"2024-01-09T13:06:04","modified_gmt":"2024-01-09T16:06:04","slug":"edital-n-002-2021-acaps-sap-processo-de-credenciamento-e-selecao-de-servidor-docente","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/edital-n-002-2021-acaps-sap-processo-de-credenciamento-e-selecao-de-servidor-docente\/","title":{"rendered":"EDITAL N.\u00ba 002\/2021\/ACAPS\/SAP &#8211; PROCESSO DE CREDENCIAMENTO E SELE\u00c7\u00c3O DE SERVIDOR DOCENTE"},"content":{"rendered":"<div style=\"text-align: justify;\">O SECRET\u00c1RIO DE ESTADO DA ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA, O DIRETOR DA ACADEMIA DE ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA E A COMISS\u00c3O DE CREDENCIAMENTO E SELE\u00c7\u00c3O, nomeada pela PORTARIA N\u00ba 001\/ACAPS\/GABS\/SAP, DE 05\/01\/2021 e altera\u00e7\u00f5es, em conformidade com o art. 6\u00ba do Decreto n.\u00ba 802, de 09 de fevereiro de 2012, faz saber, a quem interessar possa, que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo de Credenciamento e Sele\u00e7\u00e3o de Servidor Docente para atua\u00e7\u00e3o no Curso de Forma\u00e7\u00e3o Profissional de Agentes de Seguran\u00e7a Socioeducativos, do concurso p\u00fablico Edital n.\u00ba 01\/2016-SJC\/SC da Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa &#8211; SAP, que se reger\u00e1 pelas normas estabelecidas neste edital, pelo regimento interno da Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa &#8211; ACAPS e pela legisla\u00e7\u00e3o vigente.<\/div>\n<ul>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/1_edital_docentes_2021_remanescentes\/\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/2_ficha-de-inscricao_credenciamento_docentes\/\">Fica de Inscri\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/3_formulario-de-recurso_002_2021\/\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Recurso<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/4-resultado-preliminar-edital-n_-002-2021-credenciamento\/\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/5-classificagco-final-edital-n_-002-2021-credenciamento\/\" target=\"_blank\" rel=\"noopener\">Classifica\u00e7\u00e3o Final<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/6-resultado-final-edital-n_-002-2021-credenciamento\/\" target=\"_blank\" rel=\"noopener\">Resultado Final<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>O SECRET\u00c1RIO DE ESTADO DA ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA, O DIRETOR DA ACADEMIA DE ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA E A COMISS\u00c3O DE CREDENCIAMENTO E SELE\u00c7\u00c3O, nomeada pela PORTARIA N\u00ba 001\/ACAPS\/GABS\/SAP, DE 05\/01\/2021 e altera\u00e7\u00f5es, em conformidade com o art. 6\u00ba do Decreto n.\u00ba 802, de 09 de fevereiro de 2012, faz saber, a quem interessar [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[42],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:14:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2127"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2127"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2127\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}