{"id":2107,"date":"2020-09-03T17:14:16","date_gmt":"2020-09-03T20:14:16","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/dispensa-de-chamamento-publico-n-001-sap-2020-deap\/"},"modified":"2024-01-02T14:51:38","modified_gmt":"2024-01-02T17:51:38","slug":"dispensa-de-chamamento-publico-n-001-sap-2020-deap","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/dispensa-de-chamamento-publico-n-001-sap-2020-deap\/","title":{"rendered":"DISPENSA DE CHAMAMENTO P\u00daBLICO N\u00ba 001\/SAP\/2020\/DEAP"},"content":{"rendered":"<div>\n<p><strong>EXTRATO DA JUSTIFICATIVA DE DISPENSA DE CHAMAMENTO P\u00daBLICO N\u00ba 001\/SAP\/2020\/DEAP &#8211; PARCERIA LABORAL<\/strong><\/p>\n<\/div>\n<p style=\"text-align: justify;\">A Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, considerando a necessidade de manter as parcerias laborais com o Estado que j\u00e1 est\u00e3o estabelecidas durante os \u00faltimos 5 (cinco) anos, portanto, adequadas e adaptadas aos espa\u00e7os ofertados, \u00e0s rotinas de trabalho e \u00e0 seguran\u00e7a das unidades; investiga\u00e7\u00e3o e aprova\u00e7\u00e3o dos servidores indicados pelas empresas que trabalham no interior das Oficinas Laborais junto aos reeducandos; considerando que a escolha de outros parceiros com vig\u00eancia de curto espa\u00e7o de tempo acarretaria, al\u00e9m da suspens\u00e3o dos trabalhos, o risco de seguran\u00e7a na transi\u00e7\u00e3o e solu\u00e7\u00e3o de continuidade; considerando as propostas apresentadas pelos parceiros privados; conforme demonstrado, a manuten\u00e7\u00e3o das parcerias possui inquestion\u00e1vel interesse da Administra\u00e7\u00e3o. Neste cen\u00e1rio, a perman\u00eancia dos atores torna-se imprescind\u00edvel para que n\u00e3o haja preju\u00edzo da pol\u00edtica implementada, pois correria o risco de dissolu\u00e7\u00e3o de continuidade dos servi\u00e7os aos benefici\u00e1rios. Com base na excepcionalidade prevista no\u00a7 2\u00ba do art. 8\u00ba do Decreto Estadual n\u00ba 1.196\/2017, torna p\u00fablico o extrato da justificativa de Dispensa de Chamamento P\u00fablico nos termos do art. 32 da Lei Federal 13.019\/2014.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/01_extrato-para-publicagco-da-dispensa-de-chamamento-no-site-sap-pdf\/\" target=\"_blank\" rel=\"noopener\">Extrato<\/a><a href=\"index.php\/consultas\/downloads\/chamamento-publico\/chamamento-2020\/dispensa-de-chamamento-n-001-sap-2020-deap\/1408-extrato-para-publicagco-da-dispensa-de-chamamento-no-site-sap\/file\" target=\"_blank\" rel=\"noopener\"><br \/>\n<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>EXTRATO DA JUSTIFICATIVA DE DISPENSA DE CHAMAMENTO P\u00daBLICO N\u00ba 001\/SAP\/2020\/DEAP &#8211; PARCERIA LABORAL A Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, considerando a necessidade de manter as parcerias laborais com o Estado que j\u00e1 est\u00e3o estabelecidas durante os \u00faltimos 5 (cinco) anos, portanto, adequadas e adaptadas aos espa\u00e7os ofertados, \u00e0s rotinas de trabalho e [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:54:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2107"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2107"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2107\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}