{"id":2096,"date":"2020-06-23T12:34:58","date_gmt":"2020-06-23T15:34:58","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/edital-de-processo-seletivo-simplificado-n-007-2020-protege\/"},"modified":"2024-01-12T15:32:29","modified_gmt":"2024-01-12T18:32:29","slug":"edital-de-processo-seletivo-simplificado-n-007-2020-protege","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/edital-de-processo-seletivo-simplificado-n-007-2020-protege\/","title":{"rendered":"PROCESSO SELETIVO SIMPLIFICADO N\u00ba 007\/2020 &#8211; PROTEGE"},"content":{"rendered":"<div style=\"text-align: justify;\">O SECRET\u00c1RIO DE ESTADO DA ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA, no uso de suas atribui\u00e7\u00f5es e com base no art. 2\u00ba da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas no per\u00edodo de 23 de junho de 2020 at\u00e9 \u00e0s 19 horas do dia 07 de julho de 2020, as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado para a contrata\u00e7\u00e3o de profissionais para o cargo de Assistente Social, Psic\u00f3logo e T\u00e9cnico em Atividades Administrativas, por prazo determinado, para atuar no Programa Estadual de Prote\u00e7\u00e3o, Aux\u00edlio e Assist\u00eancia \u00e0s V\u00edtimas da Viol\u00eancia e \u00e0s testemunhas Amea\u00e7adas em Santa Catarina \u2013 PROTEGE\/SC, que faz parte da estrutura organizacional desta Secretaria.<\/div>\n<ul>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/01-edital-007-2020-protege\/\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/02-ficha-de-inscricao-edital-007-2020\/\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Inscri\u00e7\u00e3o<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/03-nota-de-esclarecimentos-edital-007-2020\/\" target=\"_blank\" rel=\"noopener\">Nota de Esclarecimento<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/04-resultado-premilinar-edital-007-2020\/\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/05-relacao-de-inscricoes-indeferidas-no-processo-seletivo-simplificado-edital-007-2020-site\/\" target=\"_blank\" rel=\"noopener\">Rela\u00e7\u00e3o de Inscri\u00e7\u00f5es Indeferidas<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/06-portaria-no-757-do-resultado-final-do-processo-seletivo-simplficado-edital-007-2020-doe-por-incorrecao\/\" target=\"_blank\" rel=\"noopener\">Resultado Final<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/07-relacao-de-inscricoes-indeferidas-apos-recurso-no-processo-seletivo-simplificado-edital-007-2020-site\/\" target=\"_blank\" rel=\"noopener\">Rela\u00e7\u00e3o de Inscri\u00e7\u00f5es Indeferidas &#8211; ap\u00f3s recurso<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/08-situacao-de-convocacao-007-2020-site\/\" target=\"_blank\" rel=\"noopener\">Situa\u00e7\u00e3o de Convoca\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Recurso at\u00e9 as 19 horas, do dia 23 de julho de 2020, pelo e-mail <a href=\"mailto:processoseletivo@sap.sc.gov.br\">processoseletivo@sap.sc.gov.br<\/a>, com c\u00f3pia para <a href=\"mailto:processoseletivosapsc@gmail.com\">processoseletivosapsc@gmail.com<\/a>, da forma prevista no item 8.4.1 do Edital 007\/2020:<br \/>\n8.4.1. O candidato dever\u00e1 nomear o e-mail com a palavra RECURSO, seguida do seu nome em caixa alta, coloca\u00e7\u00e3o no Processo Seletivo, especialidade escolhida, para melhor identifica\u00e7\u00e3o no momento da an\u00e1lise da documenta\u00e7\u00e3o.<br \/>\nEx.: RECURSO FULANO DE TAL &#8211; 1\u00ba COLOCADO \u2013 ASSISTENTE SOCIAL \u2013 EDITAL 007\/2020.<\/p>\n<p>Observa\u00e7\u00e3o: caso o candidato n\u00e3o localizar seu nome em nenhuma das listas acima, o mesmo dever\u00e1 questionar o motivo pelo e-mail <a href=\"mailto:processoseletivo@sap.sc.gov.br\">processoseletivo@sap.sc.gov.br<\/a>, com c\u00f3pia para <a href=\"mailto:processoseletivosapsc@gmail.com\">processoseletivosapsc@gmail.com<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>O SECRET\u00c1RIO DE ESTADO DA ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA, no uso de suas atribui\u00e7\u00f5es e com base no art. 2\u00ba da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas no per\u00edodo de 23 de junho de 2020 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[70],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:13:19","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2096"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2096"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2096\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}