{"id":20922,"date":"2025-04-25T16:52:37","date_gmt":"2025-04-25T19:52:37","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=20922"},"modified":"2025-04-25T16:52:37","modified_gmt":"2025-04-25T19:52:37","slug":"dispensa-de-chamamento-publico-010-2024-sap-gefun","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/dispensa-de-chamamento-publico-010-2024-sap-gefun\/","title":{"rendered":"DISPENSA DE CHAMAMENTO P\u00daBLICO 010\/2024\/SAP\/GEFUN"},"content":{"rendered":"<p>Com base na excepcionalidade prevista no inciso I do art. 30 e na forma do art 32, ambos da Lei 13019\/2014, a qual se aplica subsidiariamente, quanto aos procedimentos, ao chamamento p\u00fablico para celebra\u00e7\u00e3o de parceria laboral previstas no art. 23 da Lei Complementar 809\/2022, tornar p\u00fablico o extrato da justificativa de Dispensa de Chamamento P\u00fablico a qual visa \u00e0 formaliza\u00e7\u00e3o de Parceria Laboral com a oferta de 30 vagas de trabalho aos presos do regime semiaberto da Penitenci\u00e1ria de Florian\u00f3polis, pelo prazo de 60 meses, com a empresa BECO CASTELO CONSTRU\u00c7\u00d5ES E INCORPORA\u00c7\u00d5ES LTDA, CNPJ 83.601.534\/0001-09, empresa com sede no munic\u00edpio de Florian\u00f3polis (SC).<\/p>\n<p>Fica concedido o prazo de 5 dias \u00fateis para impugna\u00e7\u00e3o (Lei 13.019\/2014).<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/01_extrato-5\/\" target=\"_blank\" rel=\"noopener\">Extrato<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Com base na excepcionalidade prevista no inciso I do art. 30 e na forma do art 32, ambos da Lei 13019\/2014, a qual se aplica subsidiariamente, quanto aos procedimentos, ao chamamento p\u00fablico para celebra\u00e7\u00e3o de parceria laboral previstas no art. 23 da Lei Complementar 809\/2022, tornar p\u00fablico o extrato da justificativa de Dispensa de Chamamento [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:05:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/20922"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=20922"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/20922\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=20922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=20922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=20922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}