{"id":2088,"date":"2020-06-05T14:53:54","date_gmt":"2020-06-05T17:53:54","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/extrato-da-justificativa-de-dispensa-de-chamamento-publico-001-2020\/"},"modified":"2020-06-05T14:53:54","modified_gmt":"2020-06-05T17:53:54","slug":"extrato-da-justificativa-de-dispensa-de-chamamento-publico-001-2020","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/extrato-da-justificativa-de-dispensa-de-chamamento-publico-001-2020\/","title":{"rendered":"DISPENSA DE CHAMAMENTO P\u00daBLICO 001\/SAP\/2020"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #282828; text-align: justify;\">A Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, considerando a necessidade de perman\u00eancia da operacionaliza\u00e7\u00e3o das centrais de penas e medidas alternativas, pelo per\u00edodo necess\u00e1rio \u00e0 conclus\u00e3o do Processo Seletivo para a contrata\u00e7\u00e3o de profissionais que atuar\u00e3o nas equipes de cada CPMA. Com base na excepcionalidade prevista no art. 8\u00ba, \u00a7 2\u00ba do Decreto Estadual n\u00ba 1196, de 21 de julho de 2017, torna p\u00fablico o extrato da justificativa de dispensa de chamamento p\u00fablico nos termos do art. 32 da Lei 13.019\/2014 conforme previsto no Processo n\u00ba SJC 31106\/2020, que visa a formaliza\u00e7\u00e3o de Parceria por 120 dias, mediante Termo de Colabora\u00e7\u00e3o a ser celebrado com o Instituto Arco \u00cdris, cujo objeto \u00e9 a operacionaliza\u00e7\u00e3o das Centrais de Penas e Medidas Alternativas nas Comarcas de Florian\u00f3polis, S\u00e3o Jos\u00e9, Blumenau, Crici\u00fama, Itaja\u00ed, Laguna, Chapec\u00f3 e Joinville. Al\u00e9m da capacidade t\u00e9cnica e gerencial instalada, o Instituto Arco \u00cdris possui inquestion\u00e1vel capacidade de execu\u00e7\u00e3o do objeto, o que fica demonstrado por meio das avalia\u00e7\u00f5es anexadas nos autos do processo supramencionado. Neste cen\u00e1rio, a perman\u00eancia dos atores torna-se imprescind\u00edvel para que n\u00e3o haja preju\u00edzo da pol\u00edtica implementada, pois acarretaria o risco de solu\u00e7\u00e3o na continuidade dos servi\u00e7os aos benefici\u00e1rios do programa. Fica estabelecido o prazo de 05 (cinco) dias \u00fateis para impugna\u00e7\u00e3o da presente justificativa.<\/span><\/p>\n<p>Florian\u00f3polis, 29 de maio de 2020.<\/p>\n<p>Leandro Ant\u00f4nio Soares Lima<br \/>Secret\u00e1rio de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa<\/p>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, considerando a necessidade de perman\u00eancia da operacionaliza\u00e7\u00e3o das centrais de penas e medidas alternativas, pelo per\u00edodo necess\u00e1rio \u00e0 conclus\u00e3o do Processo Seletivo para a contrata\u00e7\u00e3o de profissionais que atuar\u00e3o nas equipes de cada CPMA. Com base na excepcionalidade prevista no art. 8\u00ba, \u00a7 2\u00ba do Decreto [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:54:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2088"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2088"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2088\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}