{"id":19969,"date":"2024-10-10T18:58:06","date_gmt":"2024-10-10T21:58:06","guid":{"rendered":"https:\/\/www.sap.sc.gov.br\/?p=19969"},"modified":"2026-02-04T16:49:46","modified_gmt":"2026-02-04T19:49:46","slug":"processo-seletivo-simplificado-002-2024","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/processo-seletivo-simplificado-002-2024\/","title":{"rendered":"PROCESSO SELETIVO SIMPLIFICADO 002\/2024"},"content":{"rendered":"<p>O Secret\u00e1rio de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, no uso de suas atribui\u00e7\u00f5es e com base no art. 2o da Lei Complementar no 260 de 22 de janeiro de 2004, regulamentada pelo Decreto no 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas no per\u00edodo de 11 de outubro de 2024 at\u00e9 \u00e0s 19 horas do dia 24 de outubro de 2024, as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado para a contrata\u00e7\u00e3o de profissionais para o cargo de Assistente Social, Psic\u00f3logo e T\u00e9cnico em Atividades Administrativas, por prazo determinado, para a participa\u00e7\u00e3o do Projeto Mulheres Livres, vinculado \u00e0 Coordenadoria de Penas Alternativas e Apoio ao Egresso, que faz parte da estrutura organizacional desta Secretaria.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/01_edital-2024-projeto-mulheres-livres\/\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/02_ficha-de-inscricao-edital-002-2024\/\" target=\"_blank\" rel=\"noopener\">Ficha de Inscri\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/03_tecnico-adm\/\" target=\"_blank\" rel=\"noopener\">Classificados &#8211; T\u00e9cnico Administrativo<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/04_psicologo\/\" target=\"_blank\" rel=\"noopener\">Classificados &#8211; Psic\u00f3logo<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/05_assistente-social\/\" target=\"_blank\" rel=\"noopener\">Classificados &#8211; Assistente Social<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/06_indeferidos\/\" target=\"_blank\" rel=\"noopener\">Processos Indeferidos<\/a><\/li>\n<li><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/07_portaria-no-2978-doe-no-22396-de-14-11-2024\/\" target=\"_blank\" rel=\"noopener\">Resultado Final<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><span style=\"text-decoration: underline;\"><strong>1\u00aa Convoca\u00e7\u00e3o<\/strong><\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/08_1a-convocacao-do-processo-seletivo-002-2024\/\" target=\"_blank\" rel=\"noopener\">Convoca\u00e7\u00e3o e Orienta\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/09_guia-de-contratacao\/\" target=\"_blank\" rel=\"noopener\">Guia de Contrata\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/forms.gle\/wA5hRU6hKtJUooht5\">Formul\u00e1rio de Contrata\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><span style=\"text-decoration: underline;\"><strong>2\u00aa Convoca\u00e7\u00e3o<\/strong><\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/12_2a-convocacao-do-processo-seletivo-002-2024\/\">Convoca\u00e7\u00e3o e Orienta\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/12_2a-convocacao-do-processo-seletivo-002-2024\/\">Guia de Contrata\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/forms.gle\/wA5hRU6hKtJUooht5\">Formul\u00e1rio de Contrata\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n<hr \/>\n<p><span style=\"text-decoration: underline;\"><strong>3\u00aa Convoca\u00e7\u00e3o<\/strong><\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/01_3a-convocacao-do-processo-seletivo-002-2024\/\" target=\"_blank\" rel=\"noopener\">Convoca\u00e7\u00e3o e Orienta\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/02_guia-de-contratacao-4\/\" target=\"_blank\" rel=\"noopener\">Guia de Contrata\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/forms.gle\/wA5hRU6hKtJUooht5\">Formul\u00e1rio de Contrata\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/04_retificacao-da-3a-convocacao-do-processo-seletivo-002-2024\/\" target=\"_blank\" rel=\"noopener\">Retifica\u00e7\u00e3o da Convoca\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n<hr \/>\n<p><span style=\"text-decoration: underline;\"><strong>4\u00aa Convoca\u00e7\u00e3o<\/strong><\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/01_4a-convocacao-do-processo-seletivo-002-2024\/\" target=\"_blank\" rel=\"noopener\">Convoca\u00e7\u00e3o e Orienta\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/02_guia-de-contratacao-6\/\" target=\"_blank\" rel=\"noopener\">Guia de Contrata\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/forms.gle\/wA5hRU6hKtJUooht5\">Formul\u00e1rio de Contrata\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n<hr \/>\n<p><span style=\"text-decoration: underline;\"><strong>5\u00aa Convoca\u00e7\u00e3o<\/strong><\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/01_5a-convocacao-do-processo-seletivo-002-2024\/\" target=\"_blank\" rel=\"noopener\">Convoca\u00e7\u00e3o e Orienta\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/02_guia-de-contratacao-11\/\" target=\"_blank\" rel=\"noopener\">Guia de Contrata\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/03_formularios-contratacao-2\/\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Contrata\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n<hr \/>\n<p><span style=\"text-decoration: underline;\"><strong>6\u00aa Convoca\u00e7\u00e3o<\/strong><\/span><\/p>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/6a-convocacao-2\/\" target=\"_blank\" rel=\"noopener\">Convoca\u00e7\u00e3o e Orienta\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/02_guia-de-contratacao-2\/\" target=\"_blank\" rel=\"noopener\">Guia de Contrata\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/03_guia-de-contratacao\/\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rios de Contrata\u00e7\u00e3o<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>O Secret\u00e1rio de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, no uso de suas atribui\u00e7\u00f5es e com base no art. 2o da Lei Complementar no 260 de 22 de janeiro de 2004, regulamentada pelo Decreto no 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas no per\u00edodo de 11 de outubro de 2024 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1379,65],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:14:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/19969"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=19969"}],"version-history":[{"count":3,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/19969\/revisions"}],"predecessor-version":[{"id":23918,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/19969\/revisions\/23918"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=19969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=19969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=19969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}