{"id":19769,"date":"2024-08-29T14:28:59","date_gmt":"2024-08-29T17:28:59","guid":{"rendered":"https:\/\/www.sap.sc.gov.br\/?p=19769"},"modified":"2025-01-27T18:18:00","modified_gmt":"2025-01-27T21:18:00","slug":"dispensa-de-chamamento-publico-009-2024-sap-gefun","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/dispensa-de-chamamento-publico-009-2024-sap-gefun\/","title":{"rendered":"DISPENSA DE CHAMAMENTO P\u00daBLICO 009\/2024\/SAP\/GEFUN"},"content":{"rendered":"<p>Com base na excepcionalidade prevista no art 20 da Lei Complementar 809\/2022, tornar p\u00fablico o extrato da justificativa de Dispensa de Chamamento P\u00fablico a qual visa \u00e0 formaliza\u00e7\u00e3o de Parceria Laboral com a oferta de 05 vagas de trabalho EXTERNO aos presos do PRES\u00cdDIO REGIONAL DE S\u00c3O JOS\u00c9 DO CEDRO, pelo prazo de 60 meses, com as empresas WK Ind\u00fastria de Cal\u00e7ados Ltda-ME (03) e NFJ Ind\u00fastria e Com\u00e9rcio de M\u00f3veis Import e Export Ltda (02).<\/p>\n<p>Fica concedido o prazo de 5 dias para impugna\u00e7\u00e3o (Lei 13.019\/2014)<\/p>\n<ul>\n<li><a href=\"https:\/\/www.sejuri.sc.gov.br\/download\/01_extrato-da-justificativa-de-dispensa-de-chamamento-publico-1\/\" target=\"_blank\" rel=\"noopener\">Extrato<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Com base na excepcionalidade prevista no art 20 da Lei Complementar 809\/2022, tornar p\u00fablico o extrato da justificativa de Dispensa de Chamamento P\u00fablico a qual visa \u00e0 formaliza\u00e7\u00e3o de Parceria Laboral com a oferta de 05 vagas de trabalho EXTERNO aos presos do PRES\u00cdDIO REGIONAL DE S\u00c3O JOS\u00c9 DO CEDRO, pelo prazo de 60 meses, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:14:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/19769"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=19769"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/19769\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=19769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=19769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=19769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}