{"id":19632,"date":"2024-07-19T15:26:17","date_gmt":"2024-07-19T18:26:17","guid":{"rendered":"https:\/\/www.sap.sc.gov.br\/?p=19632"},"modified":"2025-01-27T18:18:48","modified_gmt":"2025-01-27T21:18:48","slug":"dispensa-de-chamamento-publico-005-2024-sap-gefun","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/dispensa-de-chamamento-publico-005-2024-sap-gefun\/","title":{"rendered":"DISPENSA DE CHAMAMENTO P\u00daBLICO 005\/2024\/SAP\/GEFUN"},"content":{"rendered":"<p>Com base na excepcionalidade prevista no inciso I do art. 30 e na forma do art 32, ambos da Lei 13049\/2014, a qual se aplica subsidiariamente, quanto aos procedimentos, ao chamamento p\u00fablico para celebra\u00e7\u00e3o de parceria laboral previstas no art. 23 da Lei Complementar 809\/2022, torna p\u00fablico o extrato da justificativa de Dispensa de Chamamento P\u00fablico (SAP 00052324\/2024), a qual visa \u00e0 formaliza\u00e7\u00e3o de Parceria Laboral com a oferta de 32 vagas de trabalho aos presos da Penitenci\u00e1ria Industrial de Blumenau, com cess\u00e3o do espa\u00e7o medindo 150m\u00b2 pelo prazo de at\u00e9 180 dias ou at\u00e9 que se conclua o processo de chamamento p\u00fablico, o que ocorrer primeiro, com a empresa Bella &amp; Co. Ltda.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a title=\"01_EXTRATO DA JUSTIFICATIVA DE DISPENSA DE CHAMAMENTO P\u00daBLICO EMERG\u00caNCIAL 005-2024\" href=\"https:\/\/www.sejuri.sc.gov.br\/download\/01_extrato-da-justificativa-de-dispensa-de-chamamento-publico-emergencial-005-2024\/\" target=\"_blank\" rel=\"noopener\">Extrato<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Com base na excepcionalidade prevista no inciso I do art. 30 e na forma do art 32, ambos da Lei 13049\/2014, a qual se aplica subsidiariamente, quanto aos procedimentos, ao chamamento p\u00fablico para celebra\u00e7\u00e3o de parceria laboral previstas no art. 23 da Lei Complementar 809\/2022, torna p\u00fablico o extrato da justificativa de Dispensa de Chamamento [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:13:05","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/19632"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=19632"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/19632\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=19632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=19632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=19632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}