{"id":1895,"date":"2020-05-27T13:30:37","date_gmt":"2020-05-27T16:30:37","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/processo-seletivo-simplificado-n-005-2020-sap-gemop\/"},"modified":"2024-01-12T17:52:03","modified_gmt":"2024-01-12T20:52:03","slug":"processo-seletivo-simplificado-n-005-2020-sap-gemop","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/processo-seletivo-simplificado-n-005-2020-sap-gemop\/","title":{"rendered":"PROCESSO SELETIVO SIMPLIFICADO N\u00ba 005\/2020\/SAP &#8211; GEMOP"},"content":{"rendered":"<div style=\"text-align: justify;\">O Secret\u00e1rio de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, no uso de suas atribui\u00e7\u00f5es e com base no art. 2\u00ba da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas no per\u00edodo de 27 de maio de 2020 at\u00e9 \u00e0s 19 horas do dia 10 de junho de 2020, as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado para a contrata\u00e7\u00e3o de profissionais para o cargo de Assistente Social, Psic\u00f3logo e T\u00e9cnico em Atividades Administrativas, por prazo determinado, para atuar no Centro de Monitora\u00e7\u00e3o Eletr\u00f4nica de Presos Provis\u00f3rios e Popula\u00e7\u00e3o Carcer\u00e1ria Vulner\u00e1vel de Santa Catarina, vinculado a Ger\u00eancia de Monitoramento e Controle Penitenci\u00e1rio (GEMOP), que faz parte da estrutura organizacional desta Secretaria.<\/div>\n<ul style=\"padding: 0px; margin: 0px 0px 10px; color: #666666; font-family: 'Helvetica Neue', Helvetica, Arial, sans-serif; font-size: 14px; font-style: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; background-color: #ffffff;\">\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/01-edital-005-2020-equipe-multiprofissional-para-o-cap\/\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/02-formulario-de-inscricao-005_2020\/\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Inscri\u00e7\u00e3o<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/03-resultado-premilinar-vagas-de-ampla-concorrencia\/\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar \u2013 Vagas de Ampla Concorr\u00eancia<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/04-resultado-premilinar-vagas-reservadas\/\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar \u2013 Vagas Reservadas<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/05-relacao-de-inscricoes-indeferidas-no-processo-seletivo-simplificado-edital-005-2020-site\/\" target=\"_blank\" rel=\"noopener\">Rela\u00e7\u00e3o de Inscri\u00e7\u00f5es Indeferidas<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/06-portaria-no-594-do-resultado-final-do-processo-seletivo-simplficado-edital-005-2020-doe\/\" target=\"_blank\" rel=\"noopener\">Resultado Final<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/07-relacao-de-inscricoes-indeferidas-apos-recurso-no-processo-seletivo-simplificado-edital-005-2020-site\/\" target=\"_blank\" rel=\"noopener\">Rela\u00e7\u00e3o de Inscri\u00e7\u00f5es Indeferidas ap\u00f3s Recurso<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/08-portaria-no-598-do-retificacao-resultado-final-do-processo-seletivo-simplficado-edital-005-2020-site\/\" target=\"_blank\" rel=\"noopener\">Retifica\u00e7\u00e3o do Resultado Final<\/a><\/li>\n<li style=\"line-height: 20px; padding: 0px; margin: 0.3em 0px 0.3em 1.6em;\"><a href=\"https:\/\/sap.sc.gov.br\/index.php\/consultas\/downloads\/processo-seletivo\/processo-seletivo-2020\/processo-seletivo-simplificado-n-005-2020-sap-g\/situacao-de-convocacao-1\">Situa\u00e7\u00e3o de Convoca\u00e7\u00e3o<\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Recurso at\u00e9 as 19 horas, do dia 22 de junho de 2020, pelo e-mail <a href=\"mailto:processoseletivo@sap.sc.gov.br\">processoseletivo@sap.sc.gov.br<\/a>, com c\u00f3pia para <a href=\"mailto:processoseletivosapsc@gmail.com\">processoseletivosapsc@gmail.com<\/a>, da forma prevista no item 8.4.1 do Edital 005\/2020:<br \/>\n8.4.1. O candidato dever\u00e1 nomear o e-mail com a palavra RECURSO, seguida do seu nome em caixa alta, coloca\u00e7\u00e3o no Processo Seletivo e o cargo, para melhor identifica\u00e7\u00e3o no momento da an\u00e1lise da documenta\u00e7\u00e3o.<br \/>\nEx.: RECURSO FULANO DE TAL &#8211; 1\u00ba COLOCADO \u2013 ASSISTENTE SOCIAL.<\/p>\n<p>Observa\u00e7\u00e3o: caso o candidato n\u00e3o localizar seu nome em nenhuma das listas acima, o mesmo dever\u00e1 questionar o motivo pelo e-mail <a href=\"mailto:processoseletivo@sap.sc.gov.br\">processoseletivo@sap.sc.gov.br<\/a>, com c\u00f3pia para <a href=\"mailto:processoseletivosapsc@gmail.com\">processoseletivosapsc@gmail.com<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>O Secret\u00e1rio de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, no uso de suas atribui\u00e7\u00f5es e com base no art. 2\u00ba da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas no per\u00edodo de 27 de maio de 2020 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[70],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:14:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1895"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1895"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1895\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}