{"id":1819,"date":"2018-04-24T18:52:19","date_gmt":"2018-04-24T21:52:19","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/processo-seletivo-simplificado-n-006-2018-sjc-unidades-do-deap\/"},"modified":"2024-01-15T14:23:53","modified_gmt":"2024-01-15T17:23:53","slug":"processo-seletivo-simplificado-n-006-2018-sjc-unidades-do-deap","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/processo-seletivo-simplificado-n-006-2018-sjc-unidades-do-deap\/","title":{"rendered":"Processo Seletivo Simplificado N\u00ba 006\/2018\/SJC &#8211; Unidades do DEAP"},"content":{"rendered":"<p style=\"text-align: justify;\">O SECRET\u00c1RIO DE ESTADO DA JUSTI\u00c7A E CIDADANIA, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado de contrata\u00e7\u00e3o de pessoal, por prazo determinado, para as Unidades do Departamento de Administra\u00e7\u00e3o Prisional (DEAP), no per\u00edodo de 24 de abril de 2018 at\u00e9 \u00e0s 17 horas do dia 10 de maio de 2018.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/01-edital-006-2018-deap\/\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li style=\"text-align: justify;\">Formul\u00e1rio de Inscri\u00e7\u00e3o<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/02-qis-edital-006-2018-sjc\/\" target=\"_blank\" rel=\"noopener\">Question\u00e1rio de Investiga\u00e7\u00e3o Social<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/03-resultado-preliminar-do-processo-seletivo-edital-006-2018-site\/\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/04-formulario-de-recurso-006-2018\/\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Recurso<\/a> &#8211; (At\u00e9 \u00e0s 19 horas do dia 24 de maio de 2018)<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/05-resultado-definitivo-do-processo-seletivo-edital-006-2018-site\/\" target=\"_blank\" rel=\"noopener\">Resultado Definitivo<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/06-resultado-final-do-processo-seletivo-edital-006-2018-site\/\" target=\"_blank\" rel=\"noopener\">Resultado Final<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/07-1a-convocacao-edital-006-2018-deap\/\" target=\"_blank\" rel=\"noopener\">1\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.sap.sc.gov.br\/en\/download\/08-2a-convocacao-edital-006-2018-deap\/\" target=\"_blank\" rel=\"noopener\">2\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>O SECRET\u00c1RIO DE ESTADO DA JUSTI\u00c7A E CIDADANIA, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado de contrata\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[54],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:14:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1819"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1819"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1819\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}