{"id":1764,"date":"2017-06-21T14:43:22","date_gmt":"2017-06-21T17:43:22","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/processo-seletivo-simplificado-n-015-2017-sjc-presidio-regional-de-lages\/"},"modified":"2017-06-21T14:43:22","modified_gmt":"2017-06-21T17:43:22","slug":"processo-seletivo-simplificado-n-015-2017-sjc-presidio-regional-de-lages","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/processo-seletivo-simplificado-n-015-2017-sjc-presidio-regional-de-lages\/","title":{"rendered":"Processo Seletivo Simplificado N\u00ba 015\/2017\/SJC &#8211; Pres\u00eddio Regional de Lages"},"content":{"rendered":"<p>A SECRET\u00c1RIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba, inciso III da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado de contrata\u00e7\u00e3o de T\u00e9cnico em Enfermagem, Cirurgi\u00e3o Dentista, Enfermeiro, Psic\u00f3logo e M\u00e9dico, por prazo determinado, para o Pres\u00eddio Regional de Lages, do Departamento de Administra\u00e7\u00e3o Prisional (DEAP), que faz parte da estrutura organizacional desta Secretaria, pelo per\u00edodo compreendido entre 21 de junho de 2017 at\u00e9 \u00e0s 17 horas do dia 07 de julho de 2017.<\/p>\n<ul>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=676&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li><a href=\"http:\/\/sistemas.sc.gov.br\/sjc\/formularios\/processoseletivo\/processo-seletivo-015-2017.asp\" target=\"_self\" rel=\"noopener\">Formul\u00e1rio de Inscri\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=677&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Question\u00e1rio de Investiga\u00e7\u00e3o Social<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=719&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=720&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Recurso<\/a>&nbsp;(at\u00e9 as 19 horas do dia 28 de julho de 2017)<\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=736&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Definitivo<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=758&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">1\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=782&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">2\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=817&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">3\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"http:\/\/www.sjc.sc.gov.br\/index.php?option=com_docman&amp;task=doc_download&amp;gid=977&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">4\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A SECRET\u00c1RIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba, inciso III da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[53],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:13:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1764"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1764"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1764\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}