{"id":1760,"date":"2017-06-19T16:34:05","date_gmt":"2017-06-19T19:34:05","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/credenciamento\/"},"modified":"2024-05-02T13:46:42","modified_gmt":"2024-05-02T16:46:42","slug":"edital-no-001-sjc-2014-medico-perito-hctp","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/edital-no-001-sjc-2014-medico-perito-hctp\/","title":{"rendered":"EDITAL N\u00ba 001\/SJC\/2014 &#8211; M\u00e9dico Perito &#8211; HCTP"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"text-align: justify;\"><strong>A SECRETARIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA<\/strong>, com sede na Rua Frei Caneca n\u00ba 400, Bairro Agron\u00f4mica, CEP 88025-000, Florian\u00f3polis \u2013 SC, inscrito no CNPJ sob o n\u00ba 01.577.780\/0001-08, por interm\u00e9dio do Departamento de Administra\u00e7\u00e3o Prisional \u2013 DEAP, faz saber a quem interessar que se encontram aberta as inscri\u00e7\u00f5es para o Credenciamento de M\u00e9dico Perito para Presta\u00e7\u00e3o de Servi\u00e7os de Per\u00edcia M\u00e9dica de Laudos de Exame de Sanidade Mental, de Depend\u00eancia Toxicol\u00f3gico e de Cessa\u00e7\u00e3o de Periculosidade, atrav\u00e9s do Hospital de Cust\u00f3dia e Tratamento Psiqui\u00e1trico &#8211; HCTP, por for\u00e7a do artigo 25 da Lei Nacional n\u00ba. 8.666\/1993.<\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=140&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=683&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Credenciados<\/a><\/p>\n<p style=\"text-align: justify;\">","protected":false},"excerpt":{"rendered":"<p>A SECRETARIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA, com sede na Rua Frei Caneca n\u00ba 400, Bairro Agron\u00f4mica, CEP 88025-000, Florian\u00f3polis \u2013 SC, inscrito no CNPJ sob o n\u00ba 01.577.780\/0001-08, por interm\u00e9dio do Departamento de Administra\u00e7\u00e3o Prisional \u2013 DEAP, faz saber a quem interessar que se encontram aberta as inscri\u00e7\u00f5es para o Credenciamento de M\u00e9dico [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[42],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:14:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1760"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1760"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1760\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}