{"id":1755,"date":"2017-05-22T16:05:29","date_gmt":"2017-05-22T19:05:29","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/processo-seletivo-simplificado-n-008-2017-sjc-farmaceutico\/"},"modified":"2017-05-22T16:05:29","modified_gmt":"2017-05-22T19:05:29","slug":"processo-seletivo-simplificado-n-008-2017-sjc-farmaceutico","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/processo-seletivo-simplificado-n-008-2017-sjc-farmaceutico\/","title":{"rendered":"Processo Seletivo Simplificado N\u00ba 008\/2017\/SJC &#8211; Farmac\u00eautico"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A SECRET\u00c1RIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA<\/strong>, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba, inciso III da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado de contrata\u00e7\u00e3o de Farmac\u00eautico, por prazo determinado, para o Hospital de Cust\u00f3dia e Tratamento Psiqui\u00e1trico, do Departamento de Administra\u00e7\u00e3o Prisional, que faz parte da estrutura organizacional desta Secretaria, pelo per\u00edodo compreendido entre o dia<strong> 22 de maio de 2017 at\u00e9 \u00e0s 17 horas do dia 09 de junho de 2017<\/strong>.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=628&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"http:\/\/sistemas.sc.gov.br\/sjc\/formularios\/processoseletivo\/processo-seletivo-008-2017.asp\" target=\"_self\" rel=\"noopener\">Formul\u00e1rio de Inscri\u00e7\u00e3o<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=629&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Question\u00e1rio de Investiga\u00e7\u00e3o Social<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=680&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar<\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=681&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Recurso<\/a>&nbsp;<span style=\"text-align: justify;\">(at\u00e9 \u00e0s 19 horas do dia 26 de maio de 2017)<\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=687&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Definitivo<\/a><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=688&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">1\u00aa Convoca\u00e7\u00e3o<\/a><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=701&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">2\u00aa Convoca\u00e7\u00e3o<\/a><\/span><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A SECRET\u00c1RIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba, inciso III da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[53],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:54:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1755"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1755"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1755\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}