{"id":1749,"date":"2017-02-13T17:38:24","date_gmt":"2017-02-13T19:38:24","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/processo-seletivo-simplificado-n-003-2017-sjc-unidades-prisionais\/"},"modified":"2017-02-13T17:38:24","modified_gmt":"2017-02-13T19:38:24","slug":"processo-seletivo-simplificado-n-003-2017-sjc-unidades-prisionais","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/processo-seletivo-simplificado-n-003-2017-sjc-unidades-prisionais\/","title":{"rendered":"Processo Seletivo Simplificado N\u00ba 003\/2017\/SJC &#8211; Unidades Prisionais"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>A SECRET\u00c1RIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA<\/strong>, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba, inciso III da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado de contrata\u00e7\u00e3o de pessoal, por prazo determinado, para a Penitenci\u00e1ria de Florian\u00f3polis, Penitenci\u00e1ria de S\u00e3o Pedro de Alc\u00e2ntara, Pres\u00eddio Masculino de Tubar\u00e3o e Pres\u00eddio Regional de Joinville, do Departamento de Administra\u00e7\u00e3o Prisional (DEAP), que faz parte da estrutura organizacional desta Secretaria, pelo per\u00edodo compreendido entre <strong>13 de fevereiro de 2017 at\u00e9 \u00e0s 17 horas do dia 03 de mar\u00e7o de 2017.<\/strong><\/p>\n<ul>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=539&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li><a href=\"http:\/\/sistemas.sc.gov.br\/sjc\/formularios\/processoseletivo\/processo-seletivo-003-2017.asp\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Inscri\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=540&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Question\u00e1rio de Investiga\u00e7\u00e3o Social<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=611&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=563&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Rela\u00e7\u00e3o de Inscri\u00e7\u00f5es Indeferidas<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=564&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Recurso<\/a> (at\u00e9 \u00e0s 19 horas do dia 20 de mar\u00e7o de 2017)<\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=577&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Rela\u00e7\u00e3o de Inscri\u00e7\u00f5es Indeferidas<\/a> &#8211; Ap\u00f3s Recurso<\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=745&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Definitivo<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=744&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Justificativa da Publica\u00e7\u00e3o do Resultado Definitivo por Incorre\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=585&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Definitivo<\/a>&nbsp;(Republicado por incorre\u00e7\u00e3o)<\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=603&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">1\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=608&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">2\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=610&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">3\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=615&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">4\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=616&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">5\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=617&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">6\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=618&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">7\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=627&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">8\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=638&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">9\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=648&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">10\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=820&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">11\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=834&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">12\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=871&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">13\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=910&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">14\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=915&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">15\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=933&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">16\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=945&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">17\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=957&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">18\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=962&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">19\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"http:\/\/www.sjc.sc.gov.br\/index.php?option=com_docman&amp;task=doc_download&amp;gid=982&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">20\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"http:\/\/www.sjc.sc.gov.br\/index.php?option=com_docman&amp;task=doc_download&amp;gid=1045&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">21\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"http:\/\/www.sjc.sc.gov.br\/index.php?option=com_docman&amp;task=doc_download&amp;gid=1051&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Nota de Esclarecimento<\/a> &#8211; Greve caminhoneiros<\/li>\n<li><a href=\"http:\/\/www.sjc.sc.gov.br\/index.php?option=com_docman&amp;task=doc_download&amp;gid=1076&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">21\u00aa Convoca\u00e7\u00e3o<\/a> &#8211;&nbsp;Ap\u00f3s cancelamento devido Greve dos Caminhoneiros<\/li>\n<li><a href=\"http:\/\/www.sjc.sc.gov.br\/index.php?option=com_docman&amp;task=doc_download&amp;gid=1107&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">22\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php\/consultas\/downloads\/processo-seletivo\/processo-seletivo-2017\/processo-seletivo-simplificado-n-003-2017-sjc-u\/1122-23-convocacao-edital-003-2017-deap\/file\" target=\"_blank\" rel=\"noopener\">23\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A SECRET\u00c1RIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba, inciso III da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[53],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:14:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1749"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1749"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1749\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}