{"id":1747,"date":"2017-01-27T16:27:05","date_gmt":"2017-01-27T18:27:05","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/processo-seletivo-simplificado-n-001-2017-sjc-hctp-presidio-regional-de-ararangua-e-presidio-masculino-de-tubarao\/"},"modified":"2017-01-27T16:27:05","modified_gmt":"2017-01-27T18:27:05","slug":"processo-seletivo-simplificado-n-001-2017-sjc-hctp-presidio-regional-de-ararangua-e-presidio-masculino-de-tubarao","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/processo-seletivo-simplificado-n-001-2017-sjc-hctp-presidio-regional-de-ararangua-e-presidio-masculino-de-tubarao\/","title":{"rendered":"Processo Seletivo Simplificado N\u00ba 001\/2017\/SJC &#8211; HCTP, Pres\u00eddio Regional de Ararangu\u00e1 e Pres\u00eddio Masculino de Tubar\u00e3o"},"content":{"rendered":"<p style=\"text-align: justify;\">A SECRET\u00c1RIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba, inciso III da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado de contrata\u00e7\u00e3o de M\u00e9dicos, por prazo determinado, para o Hospital de Cust\u00f3dia e Tratamento Psiqui\u00e1trico, para o Pres\u00eddio Regional de Ararangu\u00e1 e para o Pres\u00eddio Regional Masculino de Tubar\u00e3o, do Departamento de Administra\u00e7\u00e3o Prisional (DEAP), que fazem parte da estrutura organizacional desta Secretaria, pelo per\u00edodo compreendido entre 25 de Janeiro de 2017 at\u00e9 \u00e0s 17 horas do dia 24 de Fevereiro de 2017.<\/p>\n<ul>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=532&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li><a href=\"http:\/\/sistemas.sc.gov.br\/sjc\/formularios\/processoseletivo\/processo-seletivo-001-2017.asp\" target=\"_self\" rel=\"noopener\">Formul\u00e1rio de Inscri\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=533&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Question\u00e1rio de Investiga\u00e7\u00e3o Social<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=556&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=557&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Recurso<\/a>&nbsp;(at\u00e9 \u00e0s 19 horas do dia 10 de mar\u00e7o de 2017)<\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=559&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Definitivo<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=560&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">1\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=893&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Rela\u00e7\u00e3o de Inscri\u00e7\u00f5es Indefiridas de Credenciamento<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=892&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Lista de Credenciamento de M\u00e9dicos Peritos<\/a><\/li>\n<li><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=927&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">2\u00aa Convoca\u00e7\u00e3o<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A SECRET\u00c1RIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba, inciso III da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[53],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:13:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1747"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1747"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1747\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}