{"id":1726,"date":"2016-07-18T12:58:58","date_gmt":"2016-07-18T15:58:58","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/processo-seletivo-simplificado-n-014-2016-sjc-penitenciarias\/"},"modified":"2023-12-15T15:04:31","modified_gmt":"2023-12-15T18:04:31","slug":"processo-seletivo-simplificado-n-014-2016-sjc-penitenciarias","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/processo-seletivo-simplificado-n-014-2016-sjc-penitenciarias\/","title":{"rendered":"Processo Seletivo Simplificado N\u00ba 014\/2016\/SJC &#8211; Penitenci\u00e1rias"},"content":{"rendered":"<p style=\"text-align: justify;\">A SECRET\u00c1RIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba, inciso III da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado de contrata\u00e7\u00e3o de Farmac\u00eauticos, por prazo determinado, para a Penitenci\u00e1ria Sul, Penitenci\u00e1ria Agr\u00edcola de Chapec\u00f3, Penitenci\u00e1ria de S\u00e3o Crist\u00f3v\u00e3o do Sul, Penitenci\u00e1ria Industrial de Blumenau, Penitenci\u00e1ria de S\u00e3o Pedro de Alc\u00e2ntara e para o Pres\u00eddio Regional de Jaragu\u00e1 do Sul, do Departamento de Administra\u00e7\u00e3o Prisional, que faz parte da estrutura organizacional desta Secretaria, pelo per\u00edodo compreendido entre o dia 18 de julho de 2016 at\u00e9 \u00e0s 17 horas do dia 02 de agosto de 2016.<\/p>\n<p style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=417&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/sistemas.sc.gov.br\/sjc\/formularios\/processoseletivo\/processo-seletivo-014-2016.asp\" target=\"_self\" rel=\"noopener\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"text-align: justify; vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/>Formul\u00e1rio de Inscri\u00e7\u00e3o<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=419&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"text-align: justify; vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/>Question\u00e1rio de Investiga\u00e7\u00e3o Social<\/a><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=429&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar<\/a><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=430&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de\u00a0Recurso<\/a> (at\u00e9 \u00e0s 19 horas do dia 17 de agosto de 2016)<\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"text-align: justify; vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=438&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">Resultado Definitivo<\/a><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"text-align: justify; vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=440&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">1\u00aa Convoca\u00e7\u00e3o<\/a><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"text-align: justify; vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=442&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">2\u00aa Convoca\u00e7\u00e3o<\/a><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"text-align: justify; vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=446&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">3\u00aa Convoca\u00e7\u00e3o<\/a><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"text-align: justify; vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=470&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">4\u00aa Convoca\u00e7\u00e3o<\/a><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"text-align: justify; vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=474&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">5\u00aa Convoca\u00e7\u00e3o<\/a><\/p>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-full wp-image-1629\" style=\"text-align: justify; vertical-align: bottom;\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2013\/07\/seta-pontilhada-e24.gif\" alt=\"seta-pontilhada\" width=\"8\" height=\"9\" \/><a href=\"index.php?option=com_docman&amp;task=doc_download&amp;gid=477&amp;Itemid=499\" target=\"_blank\" rel=\"noopener\">6\u00aa Convoca\u00e7\u00e3o<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>A SECRET\u00c1RIA DE ESTADO DA JUSTI\u00c7A E CIDADANIA, no uso de suas atribui\u00e7\u00f5es e com base no Art. 2\u00ba, inciso III da Lei Complementar n\u00ba 260 de 22 de janeiro de 2004, regulamentada pelo Decreto n\u00ba 1.545 de 16 de mar\u00e7o de 2004, torna p\u00fablico que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo Seletivo Simplificado [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[52],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:14:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1726"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1726"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1726\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}