{"id":1633,"date":"2013-07-31T17:31:01","date_gmt":"2013-07-31T20:31:01","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/processo-seletivo-simplificado-edital-003-2013-sjc-hctp\/"},"modified":"2013-07-31T17:31:01","modified_gmt":"2013-07-31T20:31:01","slug":"processo-seletivo-simplificado-edital-003-2013-sjc-hctp","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/processo-seletivo-simplificado-edital-003-2013-sjc-hctp\/","title":{"rendered":"Processo Seletivo Simplificado edital 003\/2013\/SJC \u2013 HCTP"},"content":{"rendered":"<div style=\"text-align: justify;\"><span style=\"font-size: 10pt;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 10pt;\">A Comiss\u00e3o do Processo Seletivo Simplificado edital 003\/2013\/SJC \u2013 HCTP, convoca os candidatos para o cargo M\u00e9dico especialista em psiquiatria listados no link abaixo a comparecerem, munidos com documentos comprobat\u00f3rios do item 6.1 do edital 003\/2013, na Ger\u00eancia de Gest\u00e3o de Pessoas da Secretaria de Estado da Justi\u00e7a e Cidadania, situada na rua Frei Caneca, n\u00ba 400, bairro Agron\u00f4mica, Florian\u00f3polis\/SC \u2013 CEP 88025-000, para contrata\u00e7\u00e3o.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 10pt;\"><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-size: 10pt;\"><strong>Arquivo para download:<\/strong> <a href=\"index.php\/consultas\/downloads\/processo-seletivo\/processo-seletivo-2013\/processo-seletivo-simplificado-n-001-2013-sjc-d\" target=\"_blank\" rel=\"noopener\">Convoca\u00e7\u00e3o<\/a><\/span><\/div>\n<div style=\"text-align: justify;\">\n<hr \/>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o do Processo Seletivo Simplificado edital 003\/2013\/SJC \u2013 HCTP, convoca os candidatos para o cargo M\u00e9dico especialista em psiquiatria listados no link abaixo a comparecerem, munidos com documentos comprobat\u00f3rios do item 6.1 do edital 003\/2013, na Ger\u00eancia de Gest\u00e3o de Pessoas da Secretaria de Estado da Justi\u00e7a e Cidadania, situada na rua Frei Caneca, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":1629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[49],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:57:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1633"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1633"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/1629"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}