{"id":15053,"date":"2022-03-04T18:20:29","date_gmt":"2022-03-04T18:20:29","guid":{"rendered":"http:\/\/webacaps2023migra.intranet.ciasc.gov.br\/2022\/03\/04\/sapciencia-aprovados-mestrado-e-doutorado-unisul\/"},"modified":"2022-03-04T18:20:29","modified_gmt":"2022-03-04T18:20:29","slug":"sapciencia-aprovados-mestrado-e-doutorado-unisul","status":"publish","type":"post","link":"https:\/\/www.sap.sc.gov.br\/en\/sapciencia-aprovados-mestrado-e-doutorado-unisul\/","title":{"rendered":"SAPCi\u00eancia &#8211; Aprovados Mestrado e Doutorado &#8211; UNISUL"},"content":{"rendered":"<\/p>\n<p>Confira a lista de candidatos APROVADOS no Processo Seletivo Stricto Sensu da Unisul, do Programa SAPCI\u00caNCIA.<\/p>\n<p><strong>Observa\u00e7\u00e3o:<\/strong><\/p>\n<p>A Unisul enviar\u00e1 um e-mail para cada candidato aprovado com as orienta\u00e7\u00f5es para a efetiva\u00e7\u00e3o da matr\u00edcula, que acontecer\u00e3o no per\u00edodo de 07 a 11 de mar\u00e7o de 2022.<\/p>\n<p style=\"text-align: justify;\">Lista dos candidatos <a href=\"\/en\/documentos\/normativas\/187-aprovados-mestrado-e-doutorado-unisul\/file\/\">(Clique aqui)<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Confira a lista de candidatos APROVADOS no Processo Seletivo Stricto Sensu da Unisul, do Programa SAPCI\u00caNCIA. Observa\u00e7\u00e3o: A Unisul enviar\u00e1 um e-mail para cada candidato aprovado com as orienta\u00e7\u00f5es para a efetiva\u00e7\u00e3o da matr\u00edcula, que acontecer\u00e3o no per\u00edodo de 07 a 11 de mar\u00e7o de 2022. Lista dos candidatos (Clique aqui).<\/p>","protected":false},"author":6,"featured_media":234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1315],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:24:17","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15053"}],"collection":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=15053"}],"version-history":[{"count":0,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=15053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=15053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=15053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}